{"id":1826,"date":"2022-05-05T19:56:54","date_gmt":"2022-05-05T17:56:54","guid":{"rendered":"http:\/\/radio.xreflector.es\/?p=1826"},"modified":"2022-05-05T19:56:54","modified_gmt":"2022-05-05T17:56:54","slug":"ccs7-que-es-eso","status":"publish","type":"post","link":"https:\/\/radio.xreflector.es\/index.php\/2022\/05\/05\/ccs7-que-es-eso\/","title":{"rendered":"CCS7 &#8211; \u00bfQu\u00e9 es eso?"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong>CCS7 BY DG1HT X-NET x-reflector<\/strong><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"657\" src=\"https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/Sin-titulo-2-1024x657.jpg\" alt=\"\" class=\"wp-image-1830\" srcset=\"https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/Sin-titulo-2-1024x657.jpg 1024w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/Sin-titulo-2-300x192.jpg 300w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/Sin-titulo-2-768x493.jpg 768w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/Sin-titulo-2.jpg 1091w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">\u00bfEl mejor servidor CCS7 para la configuraci\u00f3n regional?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">CCS701 DV4mini<br>CCS702 Alemania<br>CCS703 Suiza<br>CCS704 ircddbStart<br>CCS705 Gran Breta\u00f1a<br>CCS706 Estados Unidos de Am\u00e9rica<br>CCS707 Pa\u00edses Bajos<br>CCS710 Suecia<br>CCS711 B\u00e9lgica<br>CCS713 Noruega<br>CCS724 Estados Unidos de Am\u00e9rica 2<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"419\" src=\"https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/css2-1024x419.jpg\" alt=\"\" class=\"wp-image-1828\" srcset=\"https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/css2-1024x419.jpg 1024w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/css2-300x123.jpg 300w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/css2-768x315.jpg 768w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/css2-1536x629.jpg 1536w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/css2.jpg 1760w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"479\" src=\"https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/ccss-1024x479.jpg\" alt=\"\" class=\"wp-image-1827\" srcset=\"https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/ccss-1024x479.jpg 1024w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/ccss-300x140.jpg 300w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/ccss-768x359.jpg 768w, https:\/\/radio.xreflector.es\/wp-content\/uploads\/2022\/05\/ccss.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Usando CCS7 con una radio Icom:<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si programa memorias antiguas que configuran UrCall, RPT1 y RPT2, entonces los comandos para DPlus, DExtra y DCS son esencialmente los mismos (por ejemplo, UrCall=REF001CL, DCS006BL, XRF001AL).&nbsp;Pero para hacer conexiones CCS7, el formato es ligeramente diferente.&nbsp;El formato es: URCall=Cxxxxxxx, donde \u00abxxxxxxx\u00bb es el id CCS7 deseado correspondiente al indicativo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos estamos en medio de la transici\u00f3n del sistema CCS4 original a CCS7, pero con suerte todos pronto estar\u00e1n en CCS7, por lo que se aplica lo siguiente para usar CCS7:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ejemplo: Conectar a CCS7 id 3101234<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>&nbsp;DTMF \u00ab3101234\u00bb -o-<\/li><li>&nbsp;URCall C3101234<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Desconectarse de la conexi\u00f3n CCS7<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>&nbsp;DTMF \u201cA\u201d -o-<\/li><li>&nbsp;UrLlamar C<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nota: En las radios Icom m\u00e1s nuevas, como ID-31, ID-51, ID-5100 e IC-7100, la configuraci\u00f3n de URCall mencionada en los ejemplos anteriores se puede programar en \u00abMemoria DV\u00bb \/ \u00abSu indicativo de llamada\u00bb.&nbsp;Al hacerlo, el operador puede seleccionar la identificaci\u00f3n CCS7 deseada en el campo \u00abTO\u00bb de la pantalla del modo DR.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>Revisar:<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCCS\u00bb significa \u00abSistema de comunicaci\u00f3n indicativo de llamada\u00bb (o, a veces, Servicio de conexi\u00f3n de llamadas).&nbsp;Fue desarrollado hace varios a\u00f1os como una alternativa optimizada al sistema de enrutamiento de indicativos G2.&nbsp;El enrutamiento CCS se puede iniciar en funci\u00f3n de los indicativos, pero tambi\u00e9n en funci\u00f3n de una identificaci\u00f3n num\u00e9rica que DTMF puede ingresar f\u00e1cilmente.&nbsp;El uso de c\u00f3digos DTMF se convirti\u00f3 r\u00e1pidamente en la forma m\u00e1s com\u00fan.<br>Cuando se introdujo el c\u00f3digo CCS para el enrutamiento de indicativos DSTAR, nadie esperaba que la aceptaci\u00f3n fuera tan alta como la vemos hoy.&nbsp;Al principio, mucha gente plante\u00f3 argumentos como \u00abtenemos indicativos en radioaficionados y no necesitamos n\u00fameros\u00bb, \u00abel enrutamiento actual de indicativos G2 es lo suficientemente bueno\u00bb, etc.&nbsp;&nbsp;Sin embargo, el sistema se configur\u00f3 primero en el \u00e1rea de idioma alem\u00e1n donde el El sistema reflector DCS creci\u00f3 muy r\u00e1pido y se convirti\u00f3 en el sistema l\u00edder.<br>DCS y CCS est\u00e1n estrechamente conectados, el sistema de enrutamiento de indicativos CCS utiliza el mecanismo reflector DCS para conectar repetidores para el enrutamiento de indicativos.&nbsp;CCS Callsign Routing b\u00e1sicamente conecta 2 repetidores transparentes entre s\u00ed a trav\u00e9s de un reflector virtual.&nbsp;El sistema DTMF utiliza c\u00f3digos num\u00e9ricos de 4 d\u00edgitos que proporcionan alrededor de 9000 CCS-ID.&nbsp;Los usuarios y los repetidores comparten el mismo espacio de direcciones.&nbsp;Hacia fines de 2014 se hizo evidente que este espacio de direcciones no ser\u00e1 lo suficientemente grande para el desarrollo futuro.<br>Los usuarios de CCS vieron muchas ventajas en comparaci\u00f3n con el enrutamiento cl\u00e1sico de indicativos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>donde las llamadas se dirigen a ciegas a trav\u00e9s de repetidores sin saber si se ejecuta un QSO en el otro extremo,&nbsp;<\/li><li>donde los reflectores en ambos lados se ven perturbados por llamadas entrantes y QSO fantasmas donde solo escuchan un lado,&nbsp;<\/li><li>donde el destinatario tiene que aceptar una llamada entrante dentro de un corto per\u00edodo de tiempo antes de que pueda hablar,<\/li><li>donde se deben ingresar indicativos completos con caracteres alfab\u00e9ticos para dirigirse a alguien, lo cual es mucho m\u00e1s dif\u00edcil de hacer en muchas situaciones (como cuando se trabaja en un tel\u00e9fono m\u00f3vil) que ingresar un c\u00f3digo DTMF de 4 d\u00edgitos en el teclado DTMF del micr\u00f3fono.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de 2015 vimos algunos requisitos legales que obligaron a los administradores del sistema reflector DCS a introducir un registro b\u00e1sico para los usuarios.&nbsp;Decidieron usar el registro CCS para eso.&nbsp;Esto aument\u00f3 la demanda de CCS-ID nuevamente y se qued\u00f3 corto.&nbsp;Como primer paso, las identificaciones que no se hab\u00edan utilizado durante m\u00e1s tiempo deb\u00edan reasignarse para permitir que nuevos usuarios se registraran, lo que caus\u00f3 algunos problemas.<br>Ya pensamos en un nuevo sistema de identificaci\u00f3n para CCS en 2014, pero el hecho de que ser\u00eda necesario cambiar una gran cantidad de software de cliente siempre nos disuadi\u00f3.&nbsp;Ahora la presi\u00f3n est\u00e1 ah\u00ed, no hay otra manera, \u00a1tenemos que hacerlo!<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>Detalles de CCS7:<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora podr\u00edamos inventar un nuevo sistema, un esquema de numeraci\u00f3n propio, nuevos servidores de bases de datos, nuevos sistemas de administraci\u00f3n, reclutar nuevos administradores, crear nuevos errores y confusi\u00f3n para los usuarios.&nbsp;Pero tambi\u00e9n podr\u00edamos utilizar un sistema existente, bien dise\u00f1ado y de buen funcionamiento que est\u00e1 en uso desde hace muchos a\u00f1os.<br>Cuando el sistema de Voz Digital \u00abDMR\u00bb (Radio M\u00f3vil Digital) fue introducido a la Radioafici\u00f3n por el&nbsp;<a href=\"http:\/\/www.dmr-marc.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo MARC,<\/a>&nbsp;se enfrentaban a un sistema que no fue desarrollado para la Radioafici\u00f3n como DSTAR.&nbsp;Un hecho fue que no permit\u00eda el uso de indicativos alfanum\u00e9ricos para enrutamiento e identificaci\u00f3n.&nbsp;Sin embargo, es un muy buen sistema que se adapta bien a nuestros requisitos en radioaficionados y permite muchos nuevos desarrollos y actividades.<br>Mientras tanto, el compromiso aceptado por la mayor\u00eda de las autoridades en todo el mundo es un sistema de identificaci\u00f3n num\u00e9rica que asigna una identificaci\u00f3n \u00fanica a un indicativo en una base de datos p\u00fablica legible.&nbsp;Algunos OM inteligentes definieron un esquema de ID estructurado que se basa en el \u00abC\u00f3digo de pa\u00eds m\u00f3vil de la UIT\u00bb (MCC).&nbsp;Este c\u00f3digo tambi\u00e9n se usa en muchas redes comerciales como en las redes telef\u00f3nicas.<br>El sistema de numeraci\u00f3n utiliza una estructura jer\u00e1rquica, el primer d\u00edgito representa el continente (2=Europa, 3=Norteam\u00e9rica, 4=Asia, 5=Australia\/Ocean\u00eda, 6=\u00c1frica, 7=Sudam\u00e9rica).&nbsp;Los primeros 3 d\u00edgitos identifican el pa\u00eds, por ejemplo, 235 para el Reino Unido, 262 para Alemania, 310-319 para los Estados Unidos, 655 para Sud\u00e1frica, etc.&nbsp;&nbsp;En la radioafici\u00f3n usamos 4 d\u00edgitos m\u00e1s para ID de usuario, 3 d\u00edgitos m\u00e1s para Identificaciones de repetidores.&nbsp;Algunos pa\u00edses usan 1 d\u00edgito despu\u00e9s del MCC para una estructura regional como para los estados, Kantone, Bundesl\u00e4nder.<br>Encuentre m\u00e1s informaci\u00f3n sobre ITU-MCC en&nbsp;<a href=\"http:\/\/en.wikipedia.org\/wiki\/Mobile_Country_Code\" target=\"_blank\" rel=\"noreferrer noopener\">Wikipedia<\/a>&nbsp;y en las p\u00e1ginas web de&nbsp;<a href=\"http:\/\/www.itu.int\/en\/ITU-T\/inr\/Pages\/default.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">ITU<\/a>&nbsp;.<br>Puede encontrar una lista completa de ID que se utilizan para radioaficionados aqu\u00ed:&nbsp;<a href=\"http:\/\/register.ham-digital.net\/prefix-ids.php\" target=\"_blank\" rel=\"noreferrer noopener\">ITU-MCC por pa\u00eds\/prefijo aqu\u00ed<\/a>&nbsp;e&nbsp;<a href=\"http:\/\/register.ham-digital.net\/reg-ids.php\" target=\"_blank\" rel=\"noreferrer noopener\">ID regionales aqu\u00ed<\/a>&nbsp;.<br>Este sistema proporciona alrededor de 10000 identificaciones&nbsp;por pa\u00eds&nbsp;, muchas, muchas m\u00e1s que el antiguo sistema CCS.&nbsp;(Actualmente tenemos 45000 usuarios de DSTAR en todo el mundo registrados en el sistema US-Trust y alrededor de 16000 registros de DMR en todo el mundo).&nbsp;Desde un punto de vista t\u00e9cnico, este esquema de 7 d\u00edgitos utiliza todo el espacio que est\u00e1 disponible sin cambios en el protocolo de red CCS.&nbsp;Junto con una ID de m\u00f3dulo adicional para puntos de acceso DSTAR privados, se ajusta al campo de direcci\u00f3n de 8 d\u00edgitos.<br>Hay 2 sistemas de registro (DMR-) disponibles, uno en EE. UU. para los ID de continente 3, 4, 5 y 7 y otro en Europa para los ID de continente 2 (Europa) y 6 (\u00c1frica).&nbsp;Estos sistemas de registro utilizan bases de datos sincronizadas y una base de direcciones com\u00fan: un registro \u00fanico en todo el mundo.<br>Actualmente, el sistema europeo tambi\u00e9n est\u00e1 conectado a la base de datos de DMRplus-Network.&nbsp;Se requiere un registro en uno de los 2 sistemas de registro para ser enrutado en la red DMRplus.&nbsp;El sistema europeo proporciona todas las direcciones de repetidores y usuarios registrados regulares a los DMRplus Masters y Gateways en todo el mundo.&nbsp;<br>Decidimos usar los ID de DMR existentes tambi\u00e9n como base para un nuevo esquema de ID de DSTAR y llamamos al ID de CCS de 7 d\u00edgitos \u00abCCS7\u00bb.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>ventajas:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Espacio de direcciones m\u00e1s grande<\/li><li>F\u00e1cil de usar, solo una identificaci\u00f3n para diferentes sistemas de voz digital<\/li><li>F\u00e1cil de usar con Gateways entre las redes de voz digital como aparece en la red DMRplus<\/li><li>Una estructura f\u00e1cil de manejar y coordinar<\/li><li>Base de datos existente, muchas identificaciones existentes para usuarios de DSTAR que tambi\u00e9n usan DMR<\/li><li>Un gran paso hacia una infraestructura de voz digital com\u00fan<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>Consecuencias:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>En la pr\u00e1ctica, los usuarios solo obtendr\u00e1n un nuevo CCS-ID.<\/li><li>En llamadas nacionales a usuarios, repetidores y m\u00f3dulos hotspot todo sigue igual que hoy con los c\u00f3digos de 4 y 5 d\u00edgitos.<\/li><li>El sistema CCS agrega autom\u00e1ticamente el MCC (c\u00f3digo de pa\u00eds m\u00f3vil \/ los primeros 3 d\u00edgitos) de la identificaci\u00f3n del remitente a la direcci\u00f3n de destino.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ejemplo:El DMR-ID de DL5DI es 2625007 (con MCC = 262 para Alemania)<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Una estaci\u00f3n con identificaci\u00f3n alemana puede usar el c\u00f3digo de 4 d\u00edgitos \u00ab5007\u00bb<\/li><li>Una estaci\u00f3n con una identificaci\u00f3n de otro pa\u00eds debe usar la identificaci\u00f3n completa, incluido el MCC para Alemania, \u00ab2625007\u00bb<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La forma de direccionar repetidores y m\u00f3dulos de puntos de acceso DSTAR permanece sin cambios, el MCC se agregar\u00e1 de la misma manera que se mostr\u00f3 anteriormente para los usuarios si el destino tiene otro MCC que el remitente.&nbsp;El nuevo sistema solo permitir\u00e1 utilizar 4 m\u00f3dulos diferentes (AD) para uso con DTMF.&nbsp;Proporcionaremos m\u00e1s muestras sobre esto y cambiaremos la documentaci\u00f3n existente m\u00e1s adelante.<br>Es posible que los CCS-ID actuales de 4 d\u00edgitos ya no se utilicen en el nuevo sistema; habr\u00eda muchas colisiones con los DMR-ID existentes.&nbsp;Los usuarios que ya tienen un DMR-ID registrado no necesitan cambiar nada en su registro.&nbsp;Si por alguna raz\u00f3n especial debe tener m\u00e1s de un DMR-ID registrado, \u00a1el m\u00e1s bajo ser\u00e1 el CCS7-ID!&nbsp;El sistema CCS7 no permitir\u00e1 utilizar m\u00e1s de un CCS ID por indicativo, la asignaci\u00f3n debe ser \u00fanica, la diferenciaci\u00f3n para hotspots privados o varios m\u00f3dems y dongles se puede hacer con el ID del m\u00f3dulo opcional.&nbsp;Cuando el sistema se haya implementado, apagaremos el antiguo sistema de registro de CCS.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>\u00bfQu\u00e9 hay que hacer ahora?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Debe registrarse para obtener un DMR-ID ahora.&nbsp;<br>Vaya a&nbsp;&nbsp;<a href=\"https:\/\/www.radioid.net\/#!\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.radioid.net\/#!&nbsp;<\/a>&nbsp; registrarse<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>\u00bfQu\u00e9 se ha lanzado o se puede probar hasta hoy?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Estamos avanzando paso a paso hacia el nuevo sistema.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Los servidores han sido configurados<\/li><li>Se ha lanzado una nueva versi\u00f3n de ircDDBGateway con cliente CCS7, las puertas de enlace deben actualizarse lo antes posible.<\/li><li>Las especificaciones del protocolo CCS7 est\u00e1n disponibles en el \u00e1rea de archivos del grupo de Yahoo \u00abDVRPTR\u00bb o si me las solicita (dl5di).<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a>Nuestro horario:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00a1Todos los sistemas de hardware y software que se conectan a la red CCS deben modificarse!<\/li><li>Hemos configurado los primeros servidores CCS7 nuevos y actualizaremos todos los dem\u00e1s paso a paso.<\/li><li>Jonathan G4KLX, el autor de ircDDBGateway, que es el software de puerta de enlace y repetidor DSTAR m\u00e1s com\u00fan en todo el mundo, ha lanzado el software de puerta de enlace habilitado para CCS7.<\/li><li>G4KLX ircDDBGateway&nbsp;&nbsp;est\u00e1 disponible en el grupo de Yahoo y en los servidores del repositorio.<\/li><li>El viejo sistema CCS no es compatible con el nuevo, ser\u00e1 reemplazado dentro de las pr\u00f3ximas semanas.<\/li><li>Los nombres de los nuevos servidores son CCS701, CCS702&#8230; etc.<\/li><li>Se me pueden solicitar las especificaciones del nuevo protocolo para desarrolladores (DL5DI).&nbsp;Est\u00e1 disponible en idioma ingl\u00e9s.<\/li><li>Durante la fase de transici\u00f3n, CCS y CCS7 pueden funcionar en paralelo durante un tiempo, los servidores se conectar\u00e1n y las direcciones se traducir\u00e1n, pero mantendremos este tiempo lo m\u00e1s breve posible.&nbsp;Causar\u00e1 cierta confusi\u00f3n a los usuarios porque tienen que usar ID diferentes en los diferentes sistemas para el mismo destino.&nbsp;Recomendamos que todos actualicen G4KLX&nbsp;&nbsp;ircDDBGateway lo antes posible, incluidos los&nbsp;&nbsp;administradores repetidores.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los nuevos CCS7-ID ser\u00e1n necesarios en el futuro para obtener acceso a la red reflectora DCS, como ya ocurre en varios servidores de Europa.\u00a0Esto tiene razones legales y se basa en algunas experiencias con gente est\u00fapida durante el \u00faltimo a\u00f1o.<br>21. agosto 2015<br>73 de Torsten DG1HT <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/radio.xreflector.es\/index.php\/hazte-socio-colaborador-de-x-reflector-spain\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/radio.xreflector.es\/index.php\/hazte-socio-colaborador-de-x-reflector-spain\/<\/a><\/p>\n<p>Visitas: 189<\/p>","protected":false},"excerpt":{"rendered":"<p>CCS7 BY DG1HT X-NET x-reflector \u00bfEl mejor servidor CCS7 para la configuraci\u00f3n regional? CCS701 DV4miniCCS702 AlemaniaCCS703 SuizaCCS704 ircddbStartCCS705 Gran Breta\u00f1aCCS706 Estados Unidos de Am\u00e9ricaCCS707 Pa\u00edses BajosCCS710 SueciaCCS711 B\u00e9lgicaCCS713 NoruegaCCS724 Estados Unidos de Am\u00e9rica 2 Usando CCS7 con una radio Icom: Si programa memorias antiguas que configuran UrCall, RPT1 y RPT2, entonces los comandos para DPlus, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital-digital"],"_links":{"self":[{"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/posts\/1826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/comments?post=1826"}],"version-history":[{"count":2,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/posts\/1826\/revisions"}],"predecessor-version":[{"id":1832,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/posts\/1826\/revisions\/1832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/media\/1829"}],"wp:attachment":[{"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/media?parent=1826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/categories?post=1826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio.xreflector.es\/index.php\/wp-json\/wp\/v2\/tags?post=1826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}